{"id":7949,"date":"2026-03-08T12:15:32","date_gmt":"2026-03-08T11:15:32","guid":{"rendered":"https:\/\/www.restaurantelienzo.com\/?p=7949"},"modified":"2026-03-08T12:15:35","modified_gmt":"2026-03-08T11:15:35","slug":"maria-jose-martinez-chef-de-lienzo-el-exito-no-es-abrir-mil-restaurantes-sino-disfrutar-de-mi-maternidad-y-mi-negocio-el-espanol","status":"publish","type":"post","link":"https:\/\/www.restaurantelienzo.com\/ca\/maria-jose-martinez-chef-de-lienzo-el-exito-no-es-abrir-mil-restaurantes-sino-disfrutar-de-mi-maternidad-y-mi-negocio-el-espanol\/","title":{"rendered":"Mar\u00eda Jos\u00e9 Mart\u00ednez, chef de Lienzo: &#8220;El \u00e9xito no es abrir mil restaurantes, sino disfrutar de mi maternidad y mi negocio&#8221;. El Espa\u00f1ol."},"content":{"rendered":"\n<p>Hoy la periodista de el diario El Espa\u00f1ol, Natalia Mart\u00ednez, nos regala este precioso reportaje, mejor d\u00eda imposible para enmarcar en el d\u00eda de la mujer, demostrando la complicada labor que siguen teniendo las mujeres en su d\u00eda a d\u00eda cuando adem\u00e1s son madres y se dedican a la alta cocina.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.elespanol.com\/cocinillas\/reportajes-gastronomicos\/20260308\/maria-jose-martinez-chef-lienzo-exito-no-abrir-mil-restaurantes-disfrutar-maternidad-negocio\/1003744153364_0.html\">https:\/\/www.elespanol.com\/cocinillas\/reportajes-gastronomicos\/20260308\/maria-jose-martinez-chef-lienzo-exito-no-abrir-mil-restaurantes-disfrutar-maternidad-negocio\/1003744153364_0.html<\/a><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"679\" height=\"1024\" src=\"https:\/\/www.restaurantelienzo.com\/web\/wp-content\/uploads\/2026\/03\/image-679x1024.png\" alt=\"\" class=\"wp-image-7950\" srcset=\"https:\/\/www.restaurantelienzo.com\/web\/wp-content\/uploads\/2026\/03\/image-679x1024.png 679w, https:\/\/www.restaurantelienzo.com\/web\/wp-content\/uploads\/2026\/03\/image-199x300.png 199w, https:\/\/www.restaurantelienzo.com\/web\/wp-content\/uploads\/2026\/03\/image-768x1157.png 768w, https:\/\/www.restaurantelienzo.com\/web\/wp-content\/uploads\/2026\/03\/image.png 840w\" sizes=\"(max-width: 679px) 100vw, 679px\" \/><\/figure><\/div>\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy la periodista de el diario El Espa\u00f1ol, Natalia Mart\u00ednez, nos regala este precioso reportaje, mejor d\u00eda imposible para enmarcar en el d\u00eda de la mujer, demostrando la complicada labor&#8230;<\/p>\n","protected":false},"author":3,"featured_media":7954,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39],"tags":[164,43,41,44,163,48,47,45,40,46,49,42],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mar\u00eda Jos\u00e9 Mart\u00ednez, chef de Lienzo: &quot;El \u00e9xito no es abrir mil restaurantes, sino disfrutar de mi maternidad y mi negocio&quot;. El Espa\u00f1ol. - Restaurante Lienzo Valencia \u00b7 Estrella Michelin<\/title>\n<meta name=\"description\" content=\"Maria Jos\u00e9 Mart\u00ednez en cocina y Juan Jos\u00e9 Soria capitanean el Restaurante Lienzo, cocina mediterr\u00e1nea con ingredientes locales y de temporada. Estrella Michelin 2023\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.restaurantelienzo.com\/maria-jose-martinez-chef-de-lienzo-el-exito-no-es-abrir-mil-restaurantes-sino-disfrutar-de-mi-maternidad-y-mi-negocio-el-espanol\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mar\u00eda Jos\u00e9 Mart\u00ednez, chef de Lienzo: &quot;El \u00e9xito no es abrir mil restaurantes, sino disfrutar de mi maternidad y mi negocio&quot;. El Espa\u00f1ol. - Restaurante Lienzo Valencia \u00b7 Estrella Michelin\" \/>\n<meta property=\"og:description\" content=\"Maria Jos\u00e9 Mart\u00ednez en cocina y Juan Jos\u00e9 Soria capitanean el Restaurante Lienzo, cocina mediterr\u00e1nea con ingredientes locales y de temporada. Estrella Michelin 2023\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.restaurantelienzo.com\/maria-jose-martinez-chef-de-lienzo-el-exito-no-es-abrir-mil-restaurantes-sino-disfrutar-de-mi-maternidad-y-mi-negocio-el-espanol\/\" \/>\n<meta property=\"og:site_name\" content=\"Restaurante Lienzo Valencia \u00b7 Estrella Michelin\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/restaurante.lienzo?fref=ts\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/restaurante.lienzo?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-08T11:15:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-08T11:15:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.restaurantelienzo.com\/web\/wp-content\/uploads\/2026\/03\/1003744158737_261797147_1706x960.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1706\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"restaurantelienzo\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"restaurantelienzo\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.restaurantelienzo.com\/maria-jose-martinez-chef-de-lienzo-el-exito-no-es-abrir-mil-restaurantes-sino-disfrutar-de-mi-maternidad-y-mi-negocio-el-espanol\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.restaurantelienzo.com\/maria-jose-martinez-chef-de-lienzo-el-exito-no-es-abrir-mil-restaurantes-sino-disfrutar-de-mi-maternidad-y-mi-negocio-el-espanol\/\"},\"author\":{\"name\":\"restaurantelienzo\",\"@id\":\"https:\/\/www.restaurantelienzo.com\/#\/schema\/person\/6d4a9a99f3c968b1513581f017102f5c\"},\"headline\":\"Mar\u00eda Jos\u00e9 Mart\u00ednez, chef de Lienzo: &#8220;El \u00e9xito no es abrir mil restaurantes, sino disfrutar de mi maternidad y mi negocio&#8221;. El Espa\u00f1ol.\",\"datePublished\":\"2026-03-08T11:15:32+00:00\",\"dateModified\":\"2026-03-08T11:15:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.restaurantelienzo.com\/maria-jose-martinez-chef-de-lienzo-el-exito-no-es-abrir-mil-restaurantes-sino-disfrutar-de-mi-maternidad-y-mi-negocio-el-espanol\/\"},\"wordCount\":92,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.restaurantelienzo.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.restaurantelienzo.com\/maria-jose-martinez-chef-de-lienzo-el-exito-no-es-abrir-mil-restaurantes-sino-disfrutar-de-mi-maternidad-y-mi-negocio-el-espanol\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.restaurantelienzo.com\/web\/wp-content\/uploads\/2026\/03\/1003744158737_261797147_1706x960.webp\",\"keywords\":[\"#8M\",\"Alta restauraci\u00f3n Valencia\",\"Chef M\u00aaJos\u00e9 mart\u00ednez\",\"Cocinera Espa\u00f1olas\",\"D\u00eda de la Mujer\",\"Estrella MICHELIN Valencia\",\"Estrellas MICHELIN\",\"Las mejores cocineras espa\u00f1olas\",\"Restaurante Lienzo\",\"Restaurantes con estrellas en Valencia Estrella MICHELIN\",\"Sol Repsol Valencia\",\"Valencia\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.restaurantelienzo.com\/maria-jose-martinez-chef-de-lienzo-el-exito-no-es-abrir-mil-restaurantes-sino-disfrutar-de-mi-maternidad-y-mi-negocio-el-espanol\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.restaurantelienzo.com\/maria-jose-martinez-chef-de-lienzo-el-exito-no-es-abrir-mil-restaurantes-sino-disfrutar-de-mi-maternidad-y-mi-negocio-el-espanol\/\",\"url\":\"https:\/\/www.restaurantelienzo.com\/maria-jose-martinez-chef-de-lienzo-el-exito-no-es-abrir-mil-restaurantes-sino-disfrutar-de-mi-maternidad-y-mi-negocio-el-espanol\/\",\"name\":\"Mar\u00eda Jos\u00e9 Mart\u00ednez, chef de Lienzo: \\\"El \u00e9xito no es abrir mil restaurantes, sino disfrutar de mi maternidad y mi negocio\\\". El Espa\u00f1ol. - Restaurante Lienzo Valencia \u00b7 Estrella Michelin\",\"isPartOf\":{\"@id\":\"https:\/\/www.restaurantelienzo.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.restaurantelienzo.com\/maria-jose-martinez-chef-de-lienzo-el-exito-no-es-abrir-mil-restaurantes-sino-disfrutar-de-mi-maternidad-y-mi-negocio-el-espanol\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.restaurantelienzo.com\/maria-jose-martinez-chef-de-lienzo-el-exito-no-es-abrir-mil-restaurantes-sino-disfrutar-de-mi-maternidad-y-mi-negocio-el-espanol\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.restaurantelienzo.com\/web\/wp-content\/uploads\/2026\/03\/1003744158737_261797147_1706x960.webp\",\"datePublished\":\"2026-03-08T11:15:32+00:00\",\"dateModified\":\"2026-03-08T11:15:35+00:00\",\"description\":\"Maria Jos\u00e9 Mart\u00ednez en cocina y Juan Jos\u00e9 Soria capitanean el Restaurante Lienzo, cocina mediterr\u00e1nea con ingredientes locales y de temporada. Estrella Michelin 2023\",\"breadcrumb\":{\"@id\":\"https:\/\/www.restaurantelienzo.com\/maria-jose-martinez-chef-de-lienzo-el-exito-no-es-abrir-mil-restaurantes-sino-disfrutar-de-mi-maternidad-y-mi-negocio-el-espanol\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.restaurantelienzo.com\/maria-jose-martinez-chef-de-lienzo-el-exito-no-es-abrir-mil-restaurantes-sino-disfrutar-de-mi-maternidad-y-mi-negocio-el-espanol\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/www.restaurantelienzo.com\/maria-jose-martinez-chef-de-lienzo-el-exito-no-es-abrir-mil-restaurantes-sino-disfrutar-de-mi-maternidad-y-mi-negocio-el-espanol\/#primaryimage\",\"url\":\"https:\/\/www.restaurantelienzo.com\/web\/wp-content\/uploads\/2026\/03\/1003744158737_261797147_1706x960.webp\",\"contentUrl\":\"https:\/\/www.restaurantelienzo.com\/web\/wp-content\/uploads\/2026\/03\/1003744158737_261797147_1706x960.webp\",\"width\":1706,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.restaurantelienzo.com\/maria-jose-martinez-chef-de-lienzo-el-exito-no-es-abrir-mil-restaurantes-sino-disfrutar-de-mi-maternidad-y-mi-negocio-el-espanol\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.restaurantelienzo.com\/ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mar\u00eda Jos\u00e9 Mart\u00ednez, chef de Lienzo: \u00abEl \u00e9xito no es abrir mil restaurantes, sino disfrutar de mi maternidad y mi negocio\u00bb. El Espa\u00f1ol.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.restaurantelienzo.com\/#website\",\"url\":\"https:\/\/www.restaurantelienzo.com\/\",\"name\":\"Restaurante Lienzo Valencia \u00b7 Estrella Michelin\",\"description\":\"Maria Jos\u00e9 Mart\u00ednez en cocina y Juan Jos\u00e9 Soria capitanean el Restaurante Lienzo, cocina mediterr\u00e1nea con ingredientes locales y de temporada. Estrella Michelin 2023\",\"publisher\":{\"@id\":\"https:\/\/www.restaurantelienzo.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.restaurantelienzo.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.restaurantelienzo.com\/#organization\",\"name\":\"Restaurante Lienzo\",\"url\":\"https:\/\/www.restaurantelienzo.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/www.restaurantelienzo.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.restaurantelienzo.com\/web\/wp-content\/uploads\/2022\/11\/lienzo-negro.png\",\"contentUrl\":\"https:\/\/www.restaurantelienzo.com\/web\/wp-content\/uploads\/2022\/11\/lienzo-negro.png\",\"width\":341,\"height\":103,\"caption\":\"Restaurante Lienzo\"},\"image\":{\"@id\":\"https:\/\/www.restaurantelienzo.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/restaurante.lienzo?fref=ts\",\"https:\/\/www.instagram.com\/restaurante_lienzo\/?hl=es\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.restaurantelienzo.com\/#\/schema\/person\/6d4a9a99f3c968b1513581f017102f5c\",\"name\":\"restaurantelienzo\",\"sameAs\":[\"https:\/\/www.facebook.com\/restaurante.lienzo?fref=ts\",\"https:\/\/twitter.com\/@LienzoVlc\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mar\u00eda Jos\u00e9 Mart\u00ednez, chef de Lienzo: \"El \u00e9xito no es abrir mil restaurantes, sino disfrutar de mi maternidad y mi negocio\". El Espa\u00f1ol. - Restaurante Lienzo Valencia \u00b7 Estrella Michelin","description":"Maria Jos\u00e9 Mart\u00ednez en cocina y Juan Jos\u00e9 Soria capitanean el Restaurante Lienzo, cocina mediterr\u00e1nea con ingredientes locales y de temporada. Estrella Michelin 2023","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.restaurantelienzo.com\/maria-jose-martinez-chef-de-lienzo-el-exito-no-es-abrir-mil-restaurantes-sino-disfrutar-de-mi-maternidad-y-mi-negocio-el-espanol\/","og_locale":"ca_ES","og_type":"article","og_title":"Mar\u00eda Jos\u00e9 Mart\u00ednez, chef de Lienzo: \"El \u00e9xito no es abrir mil restaurantes, sino disfrutar de mi maternidad y mi negocio\". El Espa\u00f1ol. - Restaurante Lienzo Valencia \u00b7 Estrella Michelin","og_description":"Maria Jos\u00e9 Mart\u00ednez en cocina y Juan Jos\u00e9 Soria capitanean el Restaurante Lienzo, cocina mediterr\u00e1nea con ingredientes locales y de temporada. Estrella Michelin 2023","og_url":"https:\/\/www.restaurantelienzo.com\/maria-jose-martinez-chef-de-lienzo-el-exito-no-es-abrir-mil-restaurantes-sino-disfrutar-de-mi-maternidad-y-mi-negocio-el-espanol\/","og_site_name":"Restaurante Lienzo Valencia \u00b7 Estrella Michelin","article_publisher":"https:\/\/www.facebook.com\/restaurante.lienzo?fref=ts","article_author":"https:\/\/www.facebook.com\/restaurante.lienzo?fref=ts","article_published_time":"2026-03-08T11:15:32+00:00","article_modified_time":"2026-03-08T11:15:35+00:00","og_image":[{"width":1706,"height":960,"url":"https:\/\/www.restaurantelienzo.com\/web\/wp-content\/uploads\/2026\/03\/1003744158737_261797147_1706x960.webp","type":"image\/webp"}],"author":"restaurantelienzo","twitter_misc":{"Written by":"restaurantelienzo"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.restaurantelienzo.com\/maria-jose-martinez-chef-de-lienzo-el-exito-no-es-abrir-mil-restaurantes-sino-disfrutar-de-mi-maternidad-y-mi-negocio-el-espanol\/#article","isPartOf":{"@id":"https:\/\/www.restaurantelienzo.com\/maria-jose-martinez-chef-de-lienzo-el-exito-no-es-abrir-mil-restaurantes-sino-disfrutar-de-mi-maternidad-y-mi-negocio-el-espanol\/"},"author":{"name":"restaurantelienzo","@id":"https:\/\/www.restaurantelienzo.com\/#\/schema\/person\/6d4a9a99f3c968b1513581f017102f5c"},"headline":"Mar\u00eda Jos\u00e9 Mart\u00ednez, chef de Lienzo: &#8220;El \u00e9xito no es abrir mil restaurantes, sino disfrutar de mi maternidad y mi negocio&#8221;. El Espa\u00f1ol.","datePublished":"2026-03-08T11:15:32+00:00","dateModified":"2026-03-08T11:15:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.restaurantelienzo.com\/maria-jose-martinez-chef-de-lienzo-el-exito-no-es-abrir-mil-restaurantes-sino-disfrutar-de-mi-maternidad-y-mi-negocio-el-espanol\/"},"wordCount":92,"commentCount":0,"publisher":{"@id":"https:\/\/www.restaurantelienzo.com\/#organization"},"image":{"@id":"https:\/\/www.restaurantelienzo.com\/maria-jose-martinez-chef-de-lienzo-el-exito-no-es-abrir-mil-restaurantes-sino-disfrutar-de-mi-maternidad-y-mi-negocio-el-espanol\/#primaryimage"},"thumbnailUrl":"https:\/\/www.restaurantelienzo.com\/web\/wp-content\/uploads\/2026\/03\/1003744158737_261797147_1706x960.webp","keywords":["#8M","Alta restauraci\u00f3n Valencia","Chef M\u00aaJos\u00e9 mart\u00ednez","Cocinera Espa\u00f1olas","D\u00eda de la Mujer","Estrella MICHELIN Valencia","Estrellas MICHELIN","Las mejores cocineras espa\u00f1olas","Restaurante Lienzo","Restaurantes con estrellas en Valencia Estrella MICHELIN","Sol Repsol Valencia","Valencia"],"articleSection":["Noticias"],"inLanguage":"ca","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.restaurantelienzo.com\/maria-jose-martinez-chef-de-lienzo-el-exito-no-es-abrir-mil-restaurantes-sino-disfrutar-de-mi-maternidad-y-mi-negocio-el-espanol\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.restaurantelienzo.com\/maria-jose-martinez-chef-de-lienzo-el-exito-no-es-abrir-mil-restaurantes-sino-disfrutar-de-mi-maternidad-y-mi-negocio-el-espanol\/","url":"https:\/\/www.restaurantelienzo.com\/maria-jose-martinez-chef-de-lienzo-el-exito-no-es-abrir-mil-restaurantes-sino-disfrutar-de-mi-maternidad-y-mi-negocio-el-espanol\/","name":"Mar\u00eda Jos\u00e9 Mart\u00ednez, chef de Lienzo: \"El \u00e9xito no es abrir mil restaurantes, sino disfrutar de mi maternidad y mi negocio\". El Espa\u00f1ol. - Restaurante Lienzo Valencia \u00b7 Estrella Michelin","isPartOf":{"@id":"https:\/\/www.restaurantelienzo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.restaurantelienzo.com\/maria-jose-martinez-chef-de-lienzo-el-exito-no-es-abrir-mil-restaurantes-sino-disfrutar-de-mi-maternidad-y-mi-negocio-el-espanol\/#primaryimage"},"image":{"@id":"https:\/\/www.restaurantelienzo.com\/maria-jose-martinez-chef-de-lienzo-el-exito-no-es-abrir-mil-restaurantes-sino-disfrutar-de-mi-maternidad-y-mi-negocio-el-espanol\/#primaryimage"},"thumbnailUrl":"https:\/\/www.restaurantelienzo.com\/web\/wp-content\/uploads\/2026\/03\/1003744158737_261797147_1706x960.webp","datePublished":"2026-03-08T11:15:32+00:00","dateModified":"2026-03-08T11:15:35+00:00","description":"Maria Jos\u00e9 Mart\u00ednez en cocina y Juan Jos\u00e9 Soria capitanean el Restaurante Lienzo, cocina mediterr\u00e1nea con ingredientes locales y de temporada. Estrella Michelin 2023","breadcrumb":{"@id":"https:\/\/www.restaurantelienzo.com\/maria-jose-martinez-chef-de-lienzo-el-exito-no-es-abrir-mil-restaurantes-sino-disfrutar-de-mi-maternidad-y-mi-negocio-el-espanol\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.restaurantelienzo.com\/maria-jose-martinez-chef-de-lienzo-el-exito-no-es-abrir-mil-restaurantes-sino-disfrutar-de-mi-maternidad-y-mi-negocio-el-espanol\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.restaurantelienzo.com\/maria-jose-martinez-chef-de-lienzo-el-exito-no-es-abrir-mil-restaurantes-sino-disfrutar-de-mi-maternidad-y-mi-negocio-el-espanol\/#primaryimage","url":"https:\/\/www.restaurantelienzo.com\/web\/wp-content\/uploads\/2026\/03\/1003744158737_261797147_1706x960.webp","contentUrl":"https:\/\/www.restaurantelienzo.com\/web\/wp-content\/uploads\/2026\/03\/1003744158737_261797147_1706x960.webp","width":1706,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/www.restaurantelienzo.com\/maria-jose-martinez-chef-de-lienzo-el-exito-no-es-abrir-mil-restaurantes-sino-disfrutar-de-mi-maternidad-y-mi-negocio-el-espanol\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.restaurantelienzo.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Mar\u00eda Jos\u00e9 Mart\u00ednez, chef de Lienzo: \u00abEl \u00e9xito no es abrir mil restaurantes, sino disfrutar de mi maternidad y mi negocio\u00bb. El Espa\u00f1ol."}]},{"@type":"WebSite","@id":"https:\/\/www.restaurantelienzo.com\/#website","url":"https:\/\/www.restaurantelienzo.com\/","name":"Restaurante Lienzo Valencia \u00b7 Estrella Michelin","description":"Maria Jos\u00e9 Mart\u00ednez en cocina y Juan Jos\u00e9 Soria capitanean el Restaurante Lienzo, cocina mediterr\u00e1nea con ingredientes locales y de temporada. Estrella Michelin 2023","publisher":{"@id":"https:\/\/www.restaurantelienzo.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.restaurantelienzo.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.restaurantelienzo.com\/#organization","name":"Restaurante Lienzo","url":"https:\/\/www.restaurantelienzo.com\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.restaurantelienzo.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.restaurantelienzo.com\/web\/wp-content\/uploads\/2022\/11\/lienzo-negro.png","contentUrl":"https:\/\/www.restaurantelienzo.com\/web\/wp-content\/uploads\/2022\/11\/lienzo-negro.png","width":341,"height":103,"caption":"Restaurante Lienzo"},"image":{"@id":"https:\/\/www.restaurantelienzo.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/restaurante.lienzo?fref=ts","https:\/\/www.instagram.com\/restaurante_lienzo\/?hl=es"]},{"@type":"Person","@id":"https:\/\/www.restaurantelienzo.com\/#\/schema\/person\/6d4a9a99f3c968b1513581f017102f5c","name":"restaurantelienzo","sameAs":["https:\/\/www.facebook.com\/restaurante.lienzo?fref=ts","https:\/\/twitter.com\/@LienzoVlc"]}]}},"_links":{"self":[{"href":"https:\/\/www.restaurantelienzo.com\/ca\/wp-json\/wp\/v2\/posts\/7949"}],"collection":[{"href":"https:\/\/www.restaurantelienzo.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.restaurantelienzo.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.restaurantelienzo.com\/ca\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.restaurantelienzo.com\/ca\/wp-json\/wp\/v2\/comments?post=7949"}],"version-history":[{"count":1,"href":"https:\/\/www.restaurantelienzo.com\/ca\/wp-json\/wp\/v2\/posts\/7949\/revisions"}],"predecessor-version":[{"id":7958,"href":"https:\/\/www.restaurantelienzo.com\/ca\/wp-json\/wp\/v2\/posts\/7949\/revisions\/7958"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.restaurantelienzo.com\/ca\/wp-json\/wp\/v2\/media\/7954"}],"wp:attachment":[{"href":"https:\/\/www.restaurantelienzo.com\/ca\/wp-json\/wp\/v2\/media?parent=7949"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.restaurantelienzo.com\/ca\/wp-json\/wp\/v2\/categories?post=7949"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.restaurantelienzo.com\/ca\/wp-json\/wp\/v2\/tags?post=7949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}